{"id":8607,"date":"2025-06-21T18:11:22","date_gmt":"2025-06-21T18:11:22","guid":{"rendered":"https:\/\/purisimadelrincon.mx\/boletines\/?p=8607"},"modified":"2025-06-21T18:11:27","modified_gmt":"2025-06-21T18:11:27","slug":"regidores-respaldan-votacion-en-ayuntamiento","status":"publish","type":"post","link":"https:\/\/purisimadelrincon.mx\/boletines\/2025\/06\/21\/regidores-respaldan-votacion-en-ayuntamiento\/","title":{"rendered":"REGIDORES RESPALDAN VOTACI\u00d3N EN AYUNTAMIENTO"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>Defienden su postura regidores respecto de concesi\u00f3n de locales del Mercado<\/strong><\/li>\n\n\n\n<li><strong>Ambas fueron posturas a favor<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pur\u00edsima del Rinc\u00f3n, Gto. a 21 de junio de 2025.-<\/strong> &nbsp;Aunque las votaciones de los integrantes del H. Ayuntamiento para abrir convocatoria a concesiones de locales comerciales del Mercado Municipal Manuel G. Aranda fueron distintas: unos para que se diera en 6 locales y otros para 7 locales, incluido en este \u00faltimo caso el que se encuentra en proceso legal, ambas fueron votaciones a favor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El regidor David Alberto Ortiz Trillo, expone, que durante la sesi\u00f3n del H. Ayuntamiento donde el Presidente Municipal Roberto Garc\u00eda Urbano dio el voto de desempate a favor de que solo se emita la convocatoria de concesi\u00f3n para 6 locales y quede 1 pendiente, tuvo por intenci\u00f3n \u00a0evitar una doble convocatoria, es decir, \u00a0quienes votaron por la opci\u00f3n de 7 locales y no de 6 se\u00f1alaban que deb\u00edan hacerse todas en conjunto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMi voto fue a favor de que se emitiera una sola convocatoria, el local 28 est\u00e1 en revisi\u00f3n y yo opin\u00e9 que nos di\u00e9ramos prisa para resolver ese local y as\u00ed poder emitir la convocatoria con los 7 locales, para evitar realizar dos convocatorias. Suger\u00ed tambi\u00e9n una sesi\u00f3n extraordinaria para no esperar hasta la sesi\u00f3n ordinaria\u201d, plante\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y bajo ese entendido asegur\u00f3 que votaron igualmente H\u00e9ctor Ra\u00fal P\u00e9rez, M\u00f3nica L\u00f3pez, Salvador Cruz y Maricela Alcal\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente la aprobaci\u00f3n que se emiti\u00f3 fue la respaldada por el Presidente Municipal Roberto Garc\u00eda Urbano, la S\u00edndico Claudia Arriaga y los regidores Dora Delia Fonseca, Benjam\u00edn Rodr\u00edguez y Marcela Ch\u00e1vez de emitir convocatoria para liberar concesiones del Mercado Municipal Manuel G. Aranda, de 6 locales, porque el s\u00e9ptimo quedar\u00e1 a reserva en tanto concluye la revisi\u00f3n de tipo legal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#Pur\u00edsimaDelRinc\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#TrasciendePorSuGente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/purisimadelrincon.mx\">https:\/\/purisimadelrincon.mx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pur\u00edsima del Rinc\u00f3n, Gto. a 21 de junio de 2025.- &nbsp;Aunque las votaciones de los integrantes del H. Ayuntamiento para abrir convocatoria a concesiones de locales comerciales del Mercado Municipal Manuel G. Aranda fueron distintas: unos para que se diera en 6 locales y otros para 7 locales, incluido en este \u00faltimo caso el que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6],"tags":[579],"class_list":["post-8607","post","type-post","status-publish","format-standard","hentry","category-gobierno","tag-postura"],"better_featured_image":null,"_links":{"self":[{"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/posts\/8607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/comments?post=8607"}],"version-history":[{"count":1,"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/posts\/8607\/revisions"}],"predecessor-version":[{"id":8610,"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/posts\/8607\/revisions\/8610"}],"wp:attachment":[{"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/media?parent=8607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/categories?post=8607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/purisimadelrincon.mx\/boletines\/wp-json\/wp\/v2\/tags?post=8607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}